{"id":77029,"date":"2018-03-29T23:00:48","date_gmt":"2018-03-29T23:00:48","guid":{"rendered":"https:\/\/www.internetsociety.org\/blog\/2018\/03\/apricot-2018-fellows\/"},"modified":"2025-11-13T18:39:53","modified_gmt":"2025-11-13T18:39:53","slug":"apricot-2018-fellows","status":"publish","type":"post","link":"https:\/\/www.internetsociety.org\/fr\/blog\/2018\/03\/apricot-2018-fellows\/","title":{"rendered":"Rencontrez les boursiers de APRICOT 2018"},"content":{"rendered":"<p>La conf\u00e9rence Internet r\u00e9gionale Asie-Pacifique sur les technologies op\u00e9rationnelles (APRICOT) est un \u00e9v\u00e9nement annuel qui rassemble des ing\u00e9nieurs Internet et des experts en r\u00e9seaux, des repr\u00e9sentants gouvernementaux, des chefs d&rsquo;entreprise Internet et d&rsquo;autres parties int\u00e9ress\u00e9es du monde entier. pr\u00e9sentations, discuter des politiques, et \u00e9tendre les r\u00e9seaux sociaux et professionnels avec des pairs aux vues similaires. L&rsquo;\u00e9v\u00e9nement de cette ann\u00e9e s&rsquo;est tenu \u00e0 Katmandou, au N\u00e9pal, du 19 au 28 f\u00e9vrier.<\/p>\n<p>Le Bureau Asie-Pacifique de l&rsquo;Internet Society a un partenariat \u00e0 long terme avec APRICOT et sponsorise fi\u00e8rement son <a href=\"https:\/\/2018.apricot.net\/fellowship\/fellows\/\">programme de bourses<\/a>, apportant un soutien financier aux personnes des \u00e9conomies en d\u00e9veloppement pour participer \u00e0 l&rsquo;\u00e9v\u00e9nement et contribuer aux discussions sur les op\u00e9rations Internet, les technologies et le d\u00e9veloppement.<\/p>\n<p><span class=\"button\"><a href=\"https:\/\/www.internetsociety.org\/fr\/blog\/2018\/03\/apricot-2018-fellows\/\">Pour conna\u00eetre les boursiers cliquez ici<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La conf\u00e9rence Internet r\u00e9gionale Asie-Pacifique sur les technologies op\u00e9rationnelles (APRICOT) est un \u00e9v\u00e9nement annuel qui rassemble des ing\u00e9nieurs Internet et des experts en r\u00e9seaux, des repr\u00e9sentants gouvernementaux, des chefs d&rsquo;entreprise Internet et d&rsquo;autres parties int\u00e9ress\u00e9es du monde entier. pr\u00e9sentations, discuter des politiques, et \u00e9tendre les r\u00e9seaux sociaux et professionnels avec des pairs aux vues similaires. [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":74653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[6187,5695,189,152,169,146],"tags":[3257,6215,6174,6245],"region_news_regions":[127],"content_category":[6101],"ppma_author":[4133],"class_list":["post-77029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comment-fonctionne-internet","category-communaute","category-evenements","category-ipv6-fr","category-les-normes-internet-ouvertes","category-deploy360-fr","tag-apricot-fr","tag-evenements","tag-femmes-de-la-tech","tag-ipv6","region_news_regions-asie-pacifique","content_category-blog-type"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202.png",555,202,false],"thumbnail":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202-150x150.png",150,150,true],"medium":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202-300x109.png",300,109,true],"medium_large":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202.png",555,202,false],"large":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202.png",555,202,false],"1536x1536":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202.png",555,202,false],"2048x2048":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202.png",555,202,false],"post-thumbnail":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202-250x91.png",250,91,true],"square":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202.png",555,202,false],"gform-image-choice-sm":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202.png",300,109,false],"gform-image-choice-md":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202.png",400,146,false],"gform-image-choice-lg":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/03\/APRICOT2018-blog-banner-555x202-04-01-555x202.png",555,202,false]},"uagb_author_info":{"display_name":"Naveed Haq","author_link":"https:\/\/www.internetsociety.org\/fr\/author\/haq\/"},"uagb_comment_info":0,"uagb_excerpt":"La conf\u00e9rence Internet r\u00e9gionale Asie-Pacifique sur les technologies op\u00e9rationnelles (APRICOT) est un \u00e9v\u00e9nement annuel qui rassemble des ing\u00e9nieurs Internet et des experts en r\u00e9seaux, des repr\u00e9sentants gouvernementaux, des chefs d&rsquo;entreprise Internet et d&rsquo;autres parties int\u00e9ress\u00e9es du monde entier. pr\u00e9sentations, discuter des politiques, et \u00e9tendre les r\u00e9seaux sociaux et professionnels avec des pairs aux vues similaires.\u2026","authors":[{"term_id":4133,"user_id":26,"is_guest":0,"slug":"haq","display_name":"Naveed Haq","avatar_url":{"url":"https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/10\/Naveed-Haq_2_Resized.jpg","url2x":"https:\/\/www.internetsociety.org\/wp-content\/uploads\/2018\/10\/Naveed-Haq_2_Resized.jpg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/posts\/77029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/comments?post=77029"}],"version-history":[{"count":0,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/posts\/77029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/media\/74653"}],"wp:attachment":[{"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/media?parent=77029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/categories?post=77029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/tags?post=77029"},{"taxonomy":"region_news_regions","embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/region_news_regions?post=77029"},{"taxonomy":"content_category","embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/content_category?post=77029"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/ppma_author?post=77029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}