{"id":127745,"date":"2020-12-06T18:09:32","date_gmt":"2020-12-06T18:09:32","guid":{"rendered":"http:\/\/www.internetsociety.org\/?page_id=127745"},"modified":"2023-04-28T15:20:45","modified_gmt":"2023-04-28T15:20:45","slug":"donner-aux-gens-les-moyens-de-prendre-des-initiatives","status":"publish","type":"page","link":"https:\/\/www.internetsociety.org\/fr\/action-plan\/2021\/empowering-people-to-take-action\/","title":{"rendered":"Donner aux gens les moyens de prendre des initiatives"},"content":{"rendered":"\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-00911769\" id=\"empowering-people-to-take-action\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\"><\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-image uagb-block-228e55ff ap-banner-small background-image-fallback-black\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<p class=\"has-neutral-white-color has-text-color has-18-font-size\"><a href=\"https:\/\/www.internetsociety.org\/fr\/action-plan\/2021\/\">Plan d\u2019action 2021<\/a>\u00a0\/ Donner aux gens les moyens de prendre des initiatives<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-neutral-white-color has-text-color has-60-font-size\">Donner aux gens les moyens de prendre des initiatives<\/h1>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-400f2aa9 ap-internal-content\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<p>Les gens qui font la promotion d&rsquo;Internet sont au c\u0153ur de ce que nous faisons. La force de l&rsquo;Internet Society vient de nos membres individuels, des membres organisationnels, des chapitres, des groupes d&rsquo;int\u00e9r\u00eat sp\u00e9cial (SIG), qui nous constituent. Nous travaillons en collaboration avec d&rsquo;autres communaut\u00e9s d&rsquo;int\u00e9r\u00eat, des partenaires et des alli\u00e9s pour assurer qu&rsquo;Internet se porte bien et comblent les besoins de tous les gens. Gr\u00e2ce \u00e0 cette collaboration, au volontariat, au financement et \u00e0 l&rsquo;assistance politique et technique, nous pouvons promouvoir efficacement un Internet plus grand et plus fort.<\/p>\n\n\n\n<p>En 2021, nous nous focaliserons sur l&rsquo;attraction, l&rsquo;engagement et le renforcement de toute notre communaut\u00e9 : membres individuels, membres organisationnels, chapitres et SIG. Nous formerons les gens gr\u00e2ce \u00e0 des possibilit\u00e9s d&rsquo;apprentissage et de bourses. Nous faciliterons le partage de connaissances pour soutenir notre mission, am\u00e9liorer les outils qu&rsquo;utilise notre communaut\u00e9 pour entrer en connexion avec les autres, nous rechercherons plus de partenaires et financerons des opportunit\u00e9s pour soutenir une croissance durable et un plus grand impact.<\/p>\n\n\n\n<p>Collectivement, ces \u00e9tapes donneront les moyens aux d\u00e9fenseurs d&rsquo;Internet de prendre des initiatives concert\u00e9es et d&rsquo;amplifier l&rsquo;impact positif que nous pouvons atteindre ensemble.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-48-font-size\">Soutenir la participation communautaire <\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-32-font-size\">Attirer et impliquer des membres individuels<\/h3>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Nous apporterons des engagements renouvel\u00e9s \u00e0 nos membres individuels qui \u00e9tendront leur port\u00e9e aux quatre coins du monde. Comme nous projetons d&rsquo;augmenter de 5 000 le nombres de personnes qui participent activement aux activit\u00e9s de l&rsquo;Internet Society d&rsquo;ici fin 2021, nous veillerons \u00e0 ce que les nouveaux membres potentiels aient une exp\u00e9rience int\u00e9ressante \u00e0 chaque \u00e9tape de leur voyage. Nous encouragerons tous les membres individuels en leur apportant le soutien organisationnel dont ils ont besoin pour r\u00e9ussir. Nous encouragerons la collaboration avec les membres individuels par le biais d&rsquo;un partage r\u00e9gulier d&rsquo;informations et de connaissances, de formations et d&rsquo;un engagement r\u00e9ciproque.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Fournir des informations fondamentales \u00e0 nos chapitres<\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Gr\u00e2ce \u00e0 des commentaires r\u00e9guliers, nous savons que les membres de nos chapitres souhaitent une plus grande participation \u00e0 nos projets. Pour une meilleure implication de nos chapitres en 2021, nous les aiderons \u00e0 communiquer et \u00e0 se d\u00e9fendre plus efficacement, ainsi qu&rsquo;\u00e0 sensibiliser les efforts li\u00e9s \u00e0 la croissance et au renforcement d&rsquo;Internet. Nous accomplirons ceci en \u00e9quipant 500 membres de chapitres d&rsquo;informations essentielles li\u00e9es \u00e0 nos projets de 2021.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Am\u00e9liorer la fonction des groupes d&rsquo;int\u00e9r\u00eat sp\u00e9cial <\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Les SIG offrent une implication diff\u00e9rente \u00e0 nos membres. Ils sont une plateforme mondiale pour les membres de l&rsquo;Internet Society pour rejoindre et discuter de sujets d&rsquo;int\u00e9r\u00eats partag\u00e9s \u00e0 notre communaut\u00e9, des sujets qui ne sont peut-\u00eatre pas couverts directement par nos projets actuels mais qui soutiennent notre mission et vision d&rsquo;ensemble. Cependant, historiquement, les SIG n&rsquo;ont pas toujours fonctionn\u00e9 aussi bien que la communaut\u00e9 l&rsquo;aurait voulu. En 2020, un groupe de travail de responsables de SIG a sugg\u00e9r\u00e9 une nouvelle approche quant \u00e0 la structure et la mani\u00e8re d&rsquo;op\u00e9rer des SIG. Leurs propositions comprennent des recommandations pour \u00e9tendre la participation mondiale et le soutien communautaire aux SIG, ainsi que pour am\u00e9liorer la fa\u00e7on dont leur travail est transmis \u00e0 l&rsquo;Internet Society et \u00e0 une communaut\u00e9 plus large.<\/p>\n\n\n\n<p>En comptant sur les repr\u00e9sentants de SIG actuels et sur le groupe de travail qui a d\u00e9velopp\u00e9 la proposition, nous cr\u00e9erons une structure SIG qui fonctionne efficacement. Cette nouvelle structure aura le soutien des membres de l&rsquo;Internet Society partout dans le monde, assurera la collaboration avec les chapitres et constituera une \u00e9vidente valeur ajout\u00e9e \u00e0 la communaut\u00e9. Dans ce cadre, nous \u00e9tablirons cinq th\u00e8mes pour 2022, tels qu&rsquo;identifi\u00e9s lors des consultations de la communaut\u00e9 SIG. Nous anticipons la transition r\u00e9ussie vers la nouvelle structure SIG d&rsquo;ici janvier 2022. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Renforcer nos connexions et participations communautaires<\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Notre communaut\u00e9 est compos\u00e9e de milliers d&rsquo;individus, d&rsquo;organisations et de b\u00e9n\u00e9voles \u00e9nergiques, enthousiastes et engag\u00e9s. Il est important qu&rsquo;ils soient engag\u00e9s, inform\u00e9s et connect\u00e9s alors qu&rsquo;ils apportent des changements mondiaux.<\/p>\n\n\n\n<p>Pour mieux soutenir notre communaut\u00e9, nous apporterons des am\u00e9liorations aux syst\u00e8mes logiciels sur lesquels ils s&rsquo;appuient, notamment nos syst\u00e8mes de gestion des associations et de gestion des relations. Ces am\u00e9liorations offriront une meilleure exp\u00e9rience globale \u00e0 l&rsquo;utilisateur, permettront des communications plus cibl\u00e9es et am\u00e9lioreront les \u00e9v\u00e9nements virtuels et en personne pour tous les participants. <\/p>\n\n\n\n<p>En mettant en \u0153uvre ces am\u00e9liorations, nous serons attentifs \u00e0 nos besoins futurs, y compris la capacit\u00e9 d&rsquo;aller plus loin dans notre travail. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Se concentrer sur le contenu pour soutenir la participation<\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Nos communications vers l&rsquo;ext\u00e9rieur restent une partie essentielle de notre travail. Nous avons la possibilit\u00e9 de valoriser notre mission de l&rsquo;int\u00e9rieur en maximisant la force du contenu de l&rsquo;Internet Society et en \u00e9tablissant des liens plus solides entre ce contenu et nos canaux de communication. <\/p>\n\n\n\n<p>Notre contenu, ce que nous disons et publions, est l&rsquo;un des plus grands outils que nous avons pour nous aider \u00e0 atteindre nos objectifs. C&rsquo;est ainsi que nous faisons passer nos id\u00e9es et que nous impliquons les gens dans notre mission. La mani\u00e8re dont nous cr\u00e9ons et g\u00e9rons le contenu a un impact \u00e9norme sur notre efficacit\u00e9 en tant qu&rsquo;organisation et communaut\u00e9, ainsi que sur notre efficacit\u00e9 \u00e0 conduire le changement et le soutien n\u00e9cessaires pour d\u00e9velopper Internet et le rendre plus fort.<\/p>\n\n\n\n<p>En 2021, nous mettrons en \u0153uvre un plan de contenu, une feuille de route pour am\u00e9liorer la fa\u00e7on dont nous planifions, cr\u00e9ons et distribuons le contenu de l&rsquo;Internet Society \u00e0 ceux qui peuvent nous aider \u00e0 r\u00e9aliser notre mission. Nous obtiendrons une meilleure vue des int\u00e9r\u00eats de notre public afin de fa\u00e7onner notre contenu et de cibler ceux qui peuvent faire la diff\u00e9rence de la mani\u00e8re qui soit la plus efficace. Nous le construirons pour eux et le distribuerons de mani\u00e8re m\u00e9thodique et cibl\u00e9e. Nous allons am\u00e9liorer le parcours des utilisateurs \u00e0 travers le contenu de l&rsquo;Internet Society, en veillant \u00e0 ce que nos r\u00e9sultats soient convaincants, pertinents et cr\u00e9atifs. Gr\u00e2ce \u00e0 cet effort, notre communaut\u00e9 et nos followers auront une vision plus claire des actions qu&rsquo;ils peuvent entreprendre pour contribuer \u00e0 la croissance et au renforcement d&rsquo;Internet, et des raisons pour lesquelles Internet a besoin du soutien de tous.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Renforcer l&rsquo;expertise et les capacit\u00e9s<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Mener l&rsquo;action par la connaissance<\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Learning @ Internet Society, notre programme de formation et de d\u00e9veloppement professionnel, est con\u00e7u pour am\u00e9liorer les comp\u00e9tences des personnes afin qu&rsquo;elles puissent devenir les futurs leaders de l&rsquo;Internet. Plus que des ressources de formation et d&rsquo;\u00e9ducation, c&rsquo;est un moyen de rassembler les gens pour soutenir notre mission et les doter des connaissances dont ils ont besoin pour agir.<\/p>\n\n\n\n<p>En 2021, nous offrirons plus d&rsquo;opportunit\u00e9s d&rsquo;apprentissage que jamais avec 30 cours d&rsquo;e-learning qui auront une port\u00e9e combin\u00e9e de 10 000 membres communautaires et partisans. Ces cours refl\u00e9teront les commentaires que nous avons re\u00e7ues de notre communaut\u00e9 en 2020 concernant leurs besoins en mati\u00e8re d&rsquo;apprentissage. Les sujets du cours comprendront le cryptage, la s\u00e9curit\u00e9 du routage, la gouvernance d&rsquo;Internet, la confidentialit\u00e9 et les op\u00e9rations de r\u00e9seau.<\/p>\n\n\n\n<p>En outre, Learning @ Internet Society repr\u00e9sente de mani\u00e8re unique des possibilit\u00e9s d&rsquo;accr\u00e9ditation passionnantes menant \u00e0 une participation accrue, \u00e0 la g\u00e9n\u00e9ration de revenus et \u00e0 la collaboration avec les institutions universitaires. En 2021, nous allons approfondir cette question et chercher \u00e0 nous assurer deux partenaires qui peuvent nous soutenir pour l&rsquo;accr\u00e9ditation des cours. Dans un premier temps, nous envisagerons d&rsquo;offrir des micro-certificats, largement reconnus par les organisations et les universitaires comme validant la ma\u00eetrise de comp\u00e9tences sp\u00e9cifiques par un individu.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Pr\u00e9parer les futurs d\u00e9fenseurs d&rsquo;Internet<\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Avec l&rsquo;importance croissante des questions li\u00e9es \u00e0 Internet dans les programmes internationaux, il est devenu essentiel de renforcer notre communaut\u00e9 de d\u00e9fenseurs dans le monde entier. En 2021, nous nous concentrerons sur deux programmes de bourses visant \u00e0 doter les d\u00e9cideurs, les experts techniques et les influenceurs des connaissances dont ils ont besoin pour \u00eatre de plus ardents d\u00e9fenseurs d&rsquo;un Internet ouvert, connect\u00e9 au niveau mondial, s\u00fbr et fiable.<\/p>\n\n\n\n<p>Le programme Early Career Fellowship est con\u00e7u pour les champions d&rsquo;Internet talentueux qui ont r\u00e9cemment d\u00e9but\u00e9 dans leur profession et qui ont un int\u00e9r\u00eat d\u00e9montr\u00e9 et un potentiel impressionnant pour toute une s\u00e9rie de sujets li\u00e9s \u00e0 Internet. En 2021, nous lancerons le programme Early Career Fellowship et nous nous assurerons le concours de quatre partenaires cl\u00e9s qui nous aideront \u00e0 le soutenir par un parrainage financier, une contribution au programme d&rsquo;\u00e9tudes ou le mentorat et la formation des boursiers.<\/p>\n\n\n\n<p>Le programme Mid Career Fellowship, id\u00e9al pour les professionnels plus avanc\u00e9s dans leur carri\u00e8re li\u00e9e \u00e0 Internet, commencera \u00e0 prendre forme en 2021 gr\u00e2ce \u00e0 une planification et un d\u00e9veloppement initiaux d\u00e9j\u00e0 en cours. Avec un lancement anticip\u00e9 en 2022, le programme Mid Career Fellowship servira de progression de formation pour les professionnels en activit\u00e9, les aidant \u00e0 amplifier leur impact potentiel.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Partager des connaissances de pointe<\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Nous continuerons \u00e0 organiser et \u00e0 accueillir le Symposium sur la s\u00e9curit\u00e9 des r\u00e9seaux et des syst\u00e8mes distribu\u00e9s (NDSS), une conf\u00e9rence universitaire de haut niveau ax\u00e9e sur les derni\u00e8res nouveaut\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 des r\u00e9seaux et des syst\u00e8mes distribu\u00e9s. Le NDSS est un incubateur d&rsquo;id\u00e9es et vise \u00e0 nourrir les futures g\u00e9n\u00e9rations d&rsquo;experts en s\u00e9curit\u00e9. Lors de ce symposium, des chercheurs universitaires et industriels et des praticiens de la s\u00e9curit\u00e9 du monde entier se r\u00e9unissent pour \u00e9changer des informations et partager leurs connaissances.<\/p>\n\n\n\n<p>Pour la toute premi\u00e8re fois, le NDSS sera une conf\u00e9rence virtuelle en 2021. Pour s&rsquo;assurer qu&rsquo;il reste dynamique et significatif, nous nous coordonnerons avec la communaut\u00e9 NDSS pour faire en sorte que son impact se fasse sentir bien apr\u00e8s l&rsquo;\u00e9v\u00e9nement lui-m\u00eame. Nous faciliterons au moins une collaboration entre la communaut\u00e9 de recherche NDSS et la communaut\u00e9s des normes ouvertes. Gr\u00e2ce \u00e0 ces efforts et \u00e0 d&rsquo;autres, nous visons \u00e0 maintenir la position du NDSS parmi les cinq premiers colloques de recherche universitaire sur la s\u00e9curit\u00e9 des ordinateurs et des r\u00e9seaux dans le monde.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">S\u00e9curiser des ressources pour la croissance et un plus grand impact<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Cibler la port\u00e9e pour un financement et un partenariat nouveaux et diversifi\u00e9s<\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La croissance durable reste une priorit\u00e9 de premier plan alors que nous explorons les opportunit\u00e9s pour des sources de revenus diversifi\u00e9es et le financement des subventions. L&rsquo;augmentation du financement n&rsquo;est pas seulement le moyen de d\u00e9bloquer notre potentiel pour faire plus. En cultivant un soutien financier plus large pour le travail de l&rsquo;Internet Society, nous d\u00e9montrons notre engagement en faveur de l&rsquo;inclusion et veillons \u00e0 ce que notre travail r\u00e9ponde aux besoins que d&rsquo;autres per\u00e7oivent. En 2021, nous \u00e9tendrons notre champ d&rsquo;action \u00e0 un \u00e9ventail plus large et plus diversifi\u00e9 de bailleurs de fonds potentiels, et nous diversifierons les canaux par lesquels nous collectons des fonds. Nous chercherons \u00e0 obtenir des revenus par le biais de l&rsquo;adh\u00e9sion d&rsquo;organisations, de parrainages, de subventions de fondations et d&rsquo;entreprises, de dons individuels, de programmes de jumelage d&rsquo;entreprises et Learning @ Internet Society. Gr\u00e2ce \u00e0 ce champ d&rsquo;action, qui compl\u00e8te les contributions de nos membres, nous obtiendrons 10 nouvelles sources de financement et 50 nouveaux partenaires qui participent activement \u00e0 notre travail.<\/p>\n\n\n\n<div class=\"wp-block-buttons ap-internal-content is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-neutral-white-color has-depth-green-background-color has-text-color has-background wp-element-button\" href=\"http:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/InternetSociety-ActionPlan2021-fr.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00e9l\u00e9charger le plan complet<\/a><\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-color uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-0 align uagb-block-e33d9f6a uagb-columns__columns-3 uagb-columns__max_width-theme uagb-columns__background-undefined uagb-columns__valign-undefined alignundefined ap-navbar\" id=\"browse\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-color uagb-block-30640d9f\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-ground-navy-background-color has-background wp-element-button\" href=\"https:\/\/www.internetsociety.org\/fr\/action-plan\/2021\/\" rel=\"#empowering-people-to-take-action\">Plan d&rsquo;action 2021<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-color uagb-block-191e7da7\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-neutral-white-color has-depth-blue-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.internetsociety.org\/fr\/action-plan\/2021\/growing-the-internet\/\" rel=\"#strengthening-the-internet\">D\u00e9velopper Internet<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-color uagb-block-5c47a553\"><div class=\"uagb-column__overlay\"><\/div>\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-depth-green-background-color has-background wp-element-button\" href=\"https:\/\/www.internetsociety.org\/fr\/action-plan\/2021\/strengthening-the-internet\/\" rel=\"#growing-the-internet\">Renforcer Internet<\/a><\/div>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-image uagb-block-35f53fa7 ap-member-cta background-image-fallback-black\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-822372b1\"><h2 class=\"uagb-heading-text\">Cr\u00e9er un Internet pour tout le monde partout<\/h2><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-ground-navy-color has-neutral-white-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.internetsociety.org\/fr\/become-a-member\/\">Devenir membre<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-neutral-white-color has-text-color wp-element-button\" href=\"https:\/\/www.internetsociety.org\/fr\/mission\/\" style=\"border-radius:50px\">Notre Mission<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__stack-mobile uagb-columns__valign- uagb-columns__gap-10 align uagb-block-3d34a53b uagb-columns__columns-3 uagb-columns__max_width-theme\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-3\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-c32e8f6a\"><div class=\"uagb-column__overlay\"><\/div><figure  id=\"svgItem-global\" tabindex=\"0\" aria-label=\"SVG image for number: 170,168 members\" class=\"number_wrapper\" style=\"background-color:transparent; display: block; text-align:center\"><svg aria-hidden=\"true\" role=\"img\" class=\"number number-1 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-1\"><\/use><\/svg><svg aria-hidden=\"true\" role=\"img\" class=\"number number-7 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-7\"><\/use><\/svg><svg aria-hidden=\"true\" role=\"img\" class=\"number number-0 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-0\"><\/use><\/svg><svg aria-hidden=\"true\" role=\"img\" class=\"number number-comma medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-comma\"><\/use><\/svg><svg aria-hidden=\"true\" role=\"img\" class=\"number number-1 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-1\"><\/use><\/svg><svg aria-hidden=\"true\" role=\"img\" class=\"number number-6 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-6\"><\/use><\/svg><svg aria-hidden=\"true\" role=\"img\" class=\"number number-8 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-8\"><\/use><\/svg><\/figure>\n\n\n<p class=\"has-text-align-center has-neutral-white-color has-text-color\"><strong>Membres<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-58ef8375\"><div class=\"uagb-column__overlay\"><\/div><figure  id=\"svgItem-chapters\" tabindex=\"0\" aria-label=\"SVG image for number: 126 members\" class=\"number_wrapper\" style=\"background-color:transparent; display: block; text-align:center\"><svg aria-hidden=\"true\" role=\"img\" class=\"number number-1 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-1\"><\/use><\/svg><svg aria-hidden=\"true\" role=\"img\" class=\"number number-2 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-2\"><\/use><\/svg><svg aria-hidden=\"true\" role=\"img\" class=\"number number-6 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-6\"><\/use><\/svg><\/figure>\n\n\n<p class=\"has-text-align-center has-neutral-white-color has-text-color\"><strong>Chapitres et SIG<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-0bd7580a\"><div class=\"uagb-column__overlay\"><\/div><figure  id=\"svgItem-orgs\" tabindex=\"0\" aria-label=\"SVG image for number: 83 members\" class=\"number_wrapper\" style=\"background-color:transparent; display: block; text-align:center\"><svg aria-hidden=\"true\" role=\"img\" class=\"number number-8 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-8\"><\/use><\/svg><svg aria-hidden=\"true\" role=\"img\" class=\"number number-3 medium\"><use xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xlink:href=\"#icon-3\"><\/use><\/svg><\/figure>\n\n\n<p class=\"has-text-align-center has-neutral-white-color has-text-color\"><strong>Membres de l&rsquo;organisation<\/strong><\/p>\n<\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<p class=\"has-text-align-center has-neutral-white-color has-ground-navy-background-color has-text-color has-background has-12-font-size\"><span class=\"has-small-font-size\">Droits d&rsquo;auteur:<\/span> <span style=\"color: rgb(208, 230, 218); font-size: var(--wp--preset--font-size--small) ;\">\u00a9 Internet Society, CC BY-NC-SA 4.0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous travaillons en collaboration avec d&rsquo;autres communaut\u00e9s d&rsquo;int\u00e9r\u00eat, des partenaires et des alli\u00e9s pour assurer qu&rsquo;Internet se porte bien et comblent les besoins de tous les gens.<\/p>\n","protected":false},"author":48,"featured_media":128373,"parent":127671,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-wide.php","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[118],"tags":[],"region_news_regions":[],"content_category":[],"ppma_author":[4039],"class_list":["post-127745","page","type-page","status-publish","has-post-thumbnail","hentry","category-qui-sommes-nous"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2.jpg",1440,688,false],"thumbnail":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2-150x150.jpg",150,150,true],"medium":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2-450x215.jpg",450,215,true],"medium_large":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2-768x367.jpg",768,367,true],"large":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2-1024x489.jpg",1024,489,true],"1536x1536":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2.jpg",1440,688,false],"2048x2048":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2.jpg",1440,688,false],"post-thumbnail":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2-250x119.jpg",250,119,true],"square":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2-600x600.jpg",600,600,true],"gform-image-choice-sm":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2.jpg",300,143,false],"gform-image-choice-md":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2.jpg",400,191,false],"gform-image-choice-lg":["https:\/\/www.internetsociety.org\/wp-content\/uploads\/2020\/12\/internet-futures-images-04-2.jpg",600,287,false]},"uagb_author_info":{"display_name":"Henri Wohlfarth","author_link":"https:\/\/www.internetsociety.org\/fr\/author\/wohlfarth\/"},"uagb_comment_info":0,"uagb_excerpt":"Nous travaillons en collaboration avec d'autres communaut\u00e9s d'int\u00e9r\u00eat, des partenaires et des alli\u00e9s pour assurer qu'Internet se porte bien et comblent les besoins de tous les gens.","_links":{"self":[{"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/pages\/127745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/comments?post=127745"}],"version-history":[{"count":0,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/pages\/127745\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/pages\/127671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/media\/128373"}],"wp:attachment":[{"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/media?parent=127745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/categories?post=127745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/tags?post=127745"},{"taxonomy":"region_news_regions","embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/region_news_regions?post=127745"},{"taxonomy":"content_category","embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/content_category?post=127745"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.internetsociety.org\/fr\/wp-json\/wp\/v2\/ppma_author?post=127745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}