{"id":144566,"date":"2021-06-02T14:00:00","date_gmt":"2021-06-02T14:00:00","guid":{"rendered":"https:\/\/www.internetsociety.org\/blog\/2021\/06\/la-oportunidad-que-necesita-tu-futuro-como-colabore-con-el-desarrollo-de-internet-y-mi-carrera-profesional\/"},"modified":"2025-09-16T11:18:56","modified_gmt":"2025-09-16T11:18:56","slug":"la-oportunidad-que-necesita-tu-futuro-como-colabore-con-el-desarrollo-de-internet-y-mi-carrera-profesional","status":"publish","type":"post","link":"https:\/\/www.internetsociety.org\/es\/blog\/2021\/06\/la-oportunidad-que-necesita-tu-futuro-como-colabore-con-el-desarrollo-de-internet-y-mi-carrera-profesional\/","title":{"rendered":"La oportunidad que necesita tu futuro: c\u00f3mo colabor\u00e9 con el desarrollo de Internet y mi carrera profesional"},"content":{"rendered":"\n<p>\u00bfTe has preguntado alguna vez c\u00f3mo puedes cambiar el rumbo de Internet? \u00bfQuieres compartir tus ideas sobre c\u00f3mo mantener la seguridad, la confianza y la fuerza del bien en Internet con las principales empresas tecnol\u00f3gicas, funcionarios gubernamentales y l\u00edderes expertos? \u00bfEst\u00e1s preparado para transformar tu carrera y dominar tus competencias de liderazgo a trav\u00e9s de un evento mundial de la ONU? Voy a hablar sobre el <a href=\"https:\/\/www.internetsociety.org\/policy-programs\/igf-youth-ambassadors\/\">programa de Embajadores de la Juventud del Foro de Gobernanza de Internet (IGF, por sus siglas en ingl\u00e9s)<\/a> de Internet Society.<\/p>\n\n\n\n<p>El programa es una oportunidad catalizadora para que j\u00f3venes l\u00edderes internacionales como t\u00fa hagan o\u00edr su voz en la gobernanza mundial de Internet y la tecnolog\u00eda actual.<\/p>\n\n\n\n<p>Como Embajadora de la Juventud del IGF 2020, Internet Society me ofreci\u00f3 una experiencia transformadora de educaci\u00f3n, creaci\u00f3n de redes y empoderamiento en el \u00e1mbito de la gobernanza de Internet y la tecnolog\u00eda. Esta experiencia corta ha marcado toda mi carrera profesional. He pasado de ser investigadora en temas de gobernanza de Internet y derechos digitales a activista mundial de toda la vida por la inclusi\u00f3n en Internet, la alfabetizaci\u00f3n digital y la reducci\u00f3n de la brecha digital.<\/p>\n\n\n\n<p>Puede que pienses que no est\u00e1s lo suficientemente cualificado o que no tienes una formaci\u00f3n estrictamente t\u00e9cnica o jur\u00eddica para sumarte a esta iniciativa. \u00bfSabes qu\u00e9? Fui la primera embajadora del IGF que ten\u00eda una formaci\u00f3n multidisciplinar en atenci\u00f3n sanitaria, investigaci\u00f3n, estudios de g\u00e9nero y promoci\u00f3n, con pocos conocimientos t\u00e9cnicos o jur\u00eddicos. El Foro de Gobernanza de Internet es una de las plataformas multisectoriales m\u00e1s inclusivas, especialmente para los j\u00f3venes.<\/p>\n\n\n\n<p>Para m\u00ed fue incre\u00edble e irreal poder dialogar, aprender y establecer contactos profesionales con los l\u00edderes tecnol\u00f3gicos mundiales. \u00bfTe imaginas lo que es charlar con gente como Vint Cerf, uno de los padres fundadores de Internet? \u00bfO expertos que trabajan en organizaciones como Google, Microsoft, IBM, IEEE, Amazon y el DAES de la ONU? \u00bfO los funcionarios de los gobiernos en el IGF, y los l\u00edderes juveniles de todo el mundo? Es simplemente una experiencia \u00fanica en la vida de la que te sentir\u00e1s orgulloso a lo largo de tu vida personal y profesional.<\/p>\n\n\n\n<p>El programa de Embajadores de la Juventud del IGF tambi\u00e9n ha contribuido a capacitarme para liderar y ampliar la defensa de mi organizaci\u00f3n internacional de la sociedad civil (Youth For Women) hacia un mundo con igualdad de g\u00e9nero y digitalmente inclusivo.<\/p>\n\n\n\n<p>Youth For Women consigui\u00f3 asociarse con el Instituto Republicano Internacional (IRI) gracias a los contactos que hice en el programa de Embajadores de la Juventud del IGF. Ahora hemos recibido financiaci\u00f3n y ayuda para poner en marcha una iniciativa de alfabetizaci\u00f3n digital a nivel comunitario sobre la desinformaci\u00f3n antes de las elecciones nacionales. Adem\u00e1s de nuestro proyecto sobre desinformaci\u00f3n, mi equipo y yo tambi\u00e9n abogamos por una reforma de la pol\u00edtica nacional sobre la violencia de g\u00e9nero en Irak.<\/p>\n\n\n\n<p>Ahora contamos con un miembro del Grupo Consultivo Multisectorial del IGF que forma parte del personal de Youth For Women. Adem\u00e1s, una de mis compa\u00f1eras embajadoras de la juventud del IGF 2020, Sof\u00eda Valle, trabaj\u00f3 conmigo durante el programa y le gustaron los objetivos integrados de Youth For Women para la igualdad de g\u00e9nero e inclusi\u00f3n en Internet. Ahora es nuestra encargada de redes sociales y editora de contenidos.<\/p>\n\n\n\n<p>Tambi\u00e9n soy actualmente vicepresidenta de la junta directiva de la Asociaci\u00f3n para la Salud de la Madre, el Reci\u00e9n Nacido y el Ni\u00f1o (PMNCH, por sus siglas en ingl\u00e9s) de la Organizaci\u00f3n Mundial de la Salud (OMS), sobre todo gracias a la incre\u00edble experiencia que adquir\u00ed con el programa de Embajadores de la Juventud del IGF.<\/p>\n\n\n\n<p>Mi experiencia en el Foro de Gobernanza de Internet 2020, desde la fase de contrataci\u00f3n hasta el aprendizaje de c\u00f3mo reforzar mi defensa de la igualdad de g\u00e9nero y la inclusi\u00f3n en Internet, me ha ayudado a prosperar de un mont\u00f3n de formas.<\/p>\n\n\n\n<p>Ahora te toca a ti. \u00a1<a href=\"https:\/\/www.internetsociety.org\/policy-programs\/igf-youth-ambassadors\/\">Vamos a redefinir el mundo digital juntos<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfTe has preguntado alguna vez c\u00f3mo puedes cambiar el rumbo de Internet? \u00bfQuieres compartir tus ideas sobre c\u00f3mo mantener la seguridad, la confianza y la fuerza del bien en Internet con las principales empresas tecnol\u00f3gicas, funcionarios gubernamentales y l\u00edderes expertos? \u00bfEst\u00e1s preparado para transformar tu carrera y dominar tus competencias de liderazgo a trav\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":1704,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[5694,5891],"tags":[6150,6149],"region_news_regions":[6030],"content_category":[6102],"ppma_author":[5620],"class_list":["post-144566","post","type-post","status-publish","format-standard","hentry","category-comunidad","category-gobernanza-de-internet","tag-becas","tag-exalumnos","region_news_regions-global","content_category-blog-type"],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false,"square":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Nojus Saad","author_link":"https:\/\/www.internetsociety.org\/es\/author\/saad\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00bfTe has preguntado alguna vez c\u00f3mo puedes cambiar el rumbo de Internet? \u00bfQuieres compartir tus ideas sobre c\u00f3mo mantener la seguridad, la confianza y la fuerza del bien en Internet con las principales empresas tecnol\u00f3gicas, funcionarios gubernamentales y l\u00edderes expertos? \u00bfEst\u00e1s preparado para transformar tu carrera y dominar tus competencias de liderazgo a trav\u00e9s de&hellip;","authors":[{"term_id":5620,"user_id":1704,"is_guest":0,"slug":"saad","display_name":"Nojus Saad","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/c14f36fe823a09d80f10f9d58932026868671cd71bcae7e244bf45ef076a4cba?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/posts\/144566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/users\/1704"}],"replies":[{"embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/comments?post=144566"}],"version-history":[{"count":0,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/posts\/144566\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/media?parent=144566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/categories?post=144566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/tags?post=144566"},{"taxonomy":"region_news_regions","embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/region_news_regions?post=144566"},{"taxonomy":"content_category","embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/content_category?post=144566"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/ppma_author?post=144566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}