{"id":226002,"date":"2025-06-23T13:07:39","date_gmt":"2025-06-23T13:07:39","guid":{"rendered":"https:\/\/www.internetsociety.org\/?post_type=news&#038;p=226002"},"modified":"2025-09-16T10:40:31","modified_gmt":"2025-09-16T10:40:31","slug":"lanzamiento-del-fondo-common-good-cyber-para-fortalecer-la-seguridad-de-internet-a-nivel-mundial","status":"publish","type":"news","link":"https:\/\/www.internetsociety.org\/es\/news\/declarationes\/2025\/lanzamiento-del-fondo-common-good-cyber-para-fortalecer-la-seguridad-de-internet-a-nivel-mundial\/","title":{"rendered":"Lanzamiento del Fondo Common Good Cyber para fortalecer la seguridad de Internet a nivel mundial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.internetsociety.org\/es\/\">Internet Society<\/a> (ISOC) y la <a href=\"https:\/\/globalcyberalliance.org\/es\/\">Global Cyber Alliance<\/a> (GCA), en nombre de la secretar\u00eda de Common Good Cyber, anuncian hoy el lanzamiento del <a href=\"http:\/\/www.commongoodcyber.org\/fund\">Fondo Common Good Cyber<\/a>, una iniciativa para fortalecer la ciberseguridad global mediante el apoyo a organizaciones sin fines de lucro que brindan servicios esenciales de ciberseguridad que protegen tanto a los actores de la sociedad civil como a Internet en su conjunto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta iniciativa es la primera en su tipo destinada a financiar la ciberseguridad en beneficio del bien com\u00fan\u2014para todas las personas, incluso aquellas que se encuentran en situaci\u00f3n de mayor riesgo\u2014y tiene el potencial de mejorar significativamente la ciberseguridad de miles de millones de personas en todo el mundo. Los miembros de la secretar\u00eda de Common Good Cyber \u200b\u200bque trabajan para abordar este desaf\u00edo son: Global Cyber Alliance, Cyber Threat Alliance, CyberPeace Institute, Forum of Incident Response and Security Teams, Global Forum on Cyber Expertise, Institute for Security and Technology, y Shadowserver Foundation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una\u00a0<a href=\"https:\/\/www.gov.uk\/government\/news\/joint-statement-between-the-prime-minister-of-the-united-kingdom-and-the-prime-minister-of-canada\" target=\"_blank\" rel=\"noreferrer noopener\">Declaraci\u00f3n Conjunta entre el Primer Ministro del Reino Unido y el Primer Ministro de Canad\u00e1<\/a>\u00a0emitida el 15 de junio de 2025, se anunci\u00f3 que ambos pa\u00edses invertir\u00edan en el fondo conjunto Common Good Cyber entre Canad\u00e1 y el Reino Unido. El 17 de junio, durante la Cumbre de L\u00edderes del G7 en Alberta (Canad\u00e1), todos los l\u00edderes del G7 anunciaron que apoyar\u00edan iniciativas como el fondo conjunto Common Good Cyber Canad\u00e1-Reino Unido para ayudar a los miembros de la sociedad civil que trabajan activamente para contrarrestar la amenaza de la represi\u00f3n transnacional. Aqu\u00ed puede leer la\u00a0<a href=\"https:\/\/g7.canada.ca\/en\/news-and-media\/news\/g7-leaders-statement-on-transnational-repression\/\" target=\"_blank\" rel=\"noreferrer noopener\">Declaraci\u00f3n de los l\u00edderes del G7 sobre la represi\u00f3n transnacional<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Fondo representa un hito en el avance de <a href=\"https:\/\/commongoodcyber.org\/\">Common Good Cyber<\/a>, una iniciativa global liderada por la Global Cyber \u200b\u200bAlliance, para desarrollar modelos de financiamiento sostenibles para las organizaciones y personas que trabajan para mantener la seguridad en Internet.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de ser una defensa fundamental de primera l\u00ednea para la seguridad de Internet, las organizaciones sin fines de lucro dedicadas a la ciberseguridad siguen enfrentando el desaf\u00edo de un financiamiento insuficiente y esto deja expuestos a millones de usuarios, entre ellos periodistas, defensores de los derechos humanos y otros grupos de la sociedad civil. Esta falta de financiamiento tambi\u00e9n expone al p\u00fablico en general a ciberamenazas cada vez m\u00e1s frecuentes y sofisticadas.<\/p>\n\n\n\n<div class=\"wp-block-uagb-blockquote uagb-block-72d4cd98 uagb-blockquote__skin-quotation uagb-blockquote__align-left uagb-blockquote__style-style_2 uagb-blockquote__stack-img-none\"><blockquote class=\"uagb-blockquote\"><span class=\"uagb-blockquote__icon\"><svg width=\"20\" height=\"20\" viewBox=\"0 0 32 32\"><path d=\"M7.031 14c3.866 0 7 3.134 7 7s-3.134 7-7 7-7-3.134-7-7l-0.031-1c0-7.732 6.268-14 14-14v4c-2.671 0-5.182 1.040-7.071 2.929-0.364 0.364-0.695 0.751-0.995 1.157 0.357-0.056 0.724-0.086 1.097-0.086zM25.031 14c3.866 0 7 3.134 7 7s-3.134 7-7 7-7-3.134-7-7l-0.031-1c0-7.732 6.268-14 14-14v4c-2.671 0-5.182 1.040-7.071 2.929-0.364 0.364-0.695 0.751-0.995 1.157 0.358-0.056 0.724-0.086 1.097-0.086z\"><\/path><\/svg><\/span><div class=\"uagb-blockquote__content\">Common Good Cyber \u200b\u200brepresenta un paso fundamental hacia un ecosistema de ciberseguridad m\u00e1s robusto e inclusivo. Al aumentar la resiliencia y la sostenibilidad a largo plazo de las organizaciones sin fines de lucro que trabajan en ciberseguridad, mejorar el acceso de las organizaciones de la sociedad civil y los defensores de los derechos humanos a servicios de confianza, y fomentar una mayor adopci\u00f3n de mejores pr\u00e1cticas y principios de seguridad por dise\u00f1o, el Fondo Common Good Cyber \u200b\u200bayuda a proteger y empoderar a todos los usuarios de Internet.\u00bb<\/div><footer><div class=\"uagb-blockquote__author-wrap uagb-blockquote__author-at-left\"><cite class=\"uagb-blockquote__author\">Philip Reitinger, presidente y director ejecutivo de Global Cyber Alliance<\/cite><\/div><\/footer><\/blockquote><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El Fondo apoyar\u00e1 a organizaciones sin fines de lucro que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mantengan y protejan la infraestructura digital b\u00e1sica, incluidos el DNS, el enrutamiento y los sistemas de inteligencia de amenazas, en beneficio del bien p\u00fablico;<\/li>\n\n\n\n<li>Brinden asistencia en ciberseguridad a actores de alto riesgo mediante capacitaci\u00f3n, respuesta r\u00e1pida a incidentes y herramientas gratuitas.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Estos futuros beneficiarios apoyan Internet al permitir operaciones seguras y proporcionar inteligencia global sobre amenazas. Protegen a la sociedad civil de las ciberamenazas mediante la intervenci\u00f3n directa de expertos y elevan la l\u00ednea de base de la seguridad de todo el ecosistema al respaldar la \u201cinfraestructura invisible\u201d de la que depende la sociedad civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Fondo funcionar\u00e1 bajo una estructura colaborativa. Internet Society ser\u00e1 la encargada de gestionar el fondo, mientras que un consejo asesor representativo y experto ofrecer\u00e1 orientaci\u00f3n estrat\u00e9gica. Actuando en nombre de la Secretar\u00eda de Common Good Cyber, Global Cyber \u200b\u200bAlliance liderar\u00e1 el Comit\u00e9 Asesor Estrat\u00e9gico del Fondo y, junto con los dem\u00e1s miembros de la Secretar\u00eda, participar\u00e1 en la promoci\u00f3n y divulgaci\u00f3n dentro del ecosistema m\u00e1s amplio de la ciberseguridad.<\/p>\n\n\n\n<div class=\"wp-block-uagb-blockquote uagb-block-e279d862 uagb-blockquote__skin-quotation uagb-blockquote__align-left uagb-blockquote__style-style_2 uagb-blockquote__stack-img-none\"><blockquote class=\"uagb-blockquote\"><span class=\"uagb-blockquote__icon\"><svg width=\"20\" height=\"20\" viewBox=\"0 0 32 32\"><path d=\"M7.031 14c3.866 0 7 3.134 7 7s-3.134 7-7 7-7-3.134-7-7l-0.031-1c0-7.732 6.268-14 14-14v4c-2.671 0-5.182 1.040-7.071 2.929-0.364 0.364-0.695 0.751-0.995 1.157 0.357-0.056 0.724-0.086 1.097-0.086zM25.031 14c3.866 0 7 3.134 7 7s-3.134 7-7 7-7-3.134-7-7l-0.031-1c0-7.732 6.268-14 14-14v4c-2.671 0-5.182 1.040-7.071 2.929-0.364 0.364-0.695 0.751-0.995 1.157 0.358-0.056 0.724-0.086 1.097-0.086z\"><\/path><\/svg><\/span><div class=\"uagb-blockquote__content\">Al apoyar el trabajo ben\u00e9fico y educativo de las organizaciones sin fines de lucro dedicadas a la ciberseguridad, brindamos un apoyo financiero esencial a quienes ayudan a mantener a Internet segura para todas las personas y a promover un acceso m\u00e1s inclusivo a una Internet segura y confiable.\u201d<\/div><footer><div class=\"uagb-blockquote__author-wrap uagb-blockquote__author-at-left\"><cite class=\"uagb-blockquote__author\">Sally Wentworth, presidenta y directora ejecutiva de Internet Society<\/cite><\/div><\/footer><\/blockquote><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El Fondo Common Good Cyber representa un compromiso global para proteger las primeras l\u00edneas digitales, habilitando la resiliencia local y la sostenibilidad digital a largo plazo. Al apoyar a organizaciones sin fines de lucro que promueven la ciberseguridad mediante herramientas, soluciones y plataformas, el Fondo construye una Internet m\u00e1s segura que funciona para todas las personas, en cualquier lugar del mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Internet Society y la Global Cyber \u200b\u200bAlliance est\u00e1n finalizando el marco legal y log\u00edstico del Fondo. En los pr\u00f3ximos meses compartiremos m\u00e1s informaci\u00f3n sobre el financiamiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Internet Society y la Global Cyber Alliance, en nombre de la secretar\u00eda de Common Good Cyber, anuncian el lanzamiento del Fondo Common Good Cyber, una iniciativa para fortalecer la ciberseguridad global.<\/p>\n","protected":false},"author":46,"featured_media":0,"template":"","categories":[4910,4777],"tags":[],"region_news_regions":[6030],"content_category":[6118,6097],"class_list":["post-226002","news","type-news","status-publish","hentry","category-fortalecimiento-de-internet","category-seguridad-es","region_news_regions-global","news_type-declarationes","content_category-declaraciones","content_category-news-type"],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"post-thumbnail":false,"square":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Ivana Trbovic","author_link":"https:\/\/www.internetsociety.org\/es\/author\/trbovic\/"},"uagb_comment_info":0,"uagb_excerpt":"Internet Society y la Global Cyber Alliance, en nombre de la secretar\u00eda de Common Good Cyber, anuncian el lanzamiento del Fondo Common Good Cyber, una iniciativa para fortalecer la ciberseguridad global.","_links":{"self":[{"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/news\/226002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/users\/46"}],"wp:attachment":[{"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/media?parent=226002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/categories?post=226002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/tags?post=226002"},{"taxonomy":"region_news_regions","embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/region_news_regions?post=226002"},{"taxonomy":"content_category","embeddable":true,"href":"https:\/\/www.internetsociety.org\/es\/wp-json\/wp\/v2\/content_category?post=226002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}